{"id":18198,"date":"2019-12-09T10:55:47","date_gmt":"2019-12-09T09:55:47","guid":{"rendered":"https:\/\/doosdesign.es\/productos\/dalia-t02-stool\/"},"modified":"2025-02-10T08:18:31","modified_gmt":"2025-02-10T07:18:31","slug":"dalia-t02-stool","status":"publish","type":"product","link":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/","title":{"rendered":"DALIA METAL"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2d0hd5-7c365e537b3542c3401afb69e8f3d50e\">\n.avia-section.av-2d0hd5-7c365e537b3542c3401afb69e8f3d50e{\nbackground-color:#f3f1ea;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-2d0hd5-7c365e537b3542c3401afb69e8f3d50e main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18198'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1o312xl-11a075dbb79bab79e119d2d3be315ea7\">\n#top .hr.hr-invisible.av-1o312xl-11a075dbb79bab79e119d2d3be315ea7{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-1o312xl-11a075dbb79bab79e119d2d3be315ea7 hr-invisible  avia-builder-el-1  el_before_av_heading  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l7u4qwfy-c95a2b425557d3db52cfb360d5d33af1\">\n#top .av-special-heading.av-l7u4qwfy-c95a2b425557d3db52cfb360d5d33af1{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-l7u4qwfy-c95a2b425557d3db52cfb360d5d33af1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-l7u4qwfy-c95a2b425557d3db52cfb360d5d33af1 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-l7u4qwfy-c95a2b425557d3db52cfb360d5d33af1 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-2  el_after_av_hr  avia-builder-el-last '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >DALIA<\/h1><div class='av-subheading av-subheading_below'><p>METAL STOOL.<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-1na84op-2705d1f62924f3de249101fa8016a798 entry-content-wrapper main_color av-flex-cells  avia-builder-el-3  el_after_av_section  el_before_av_layout_row  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1lhqgft-9ffe441c8ce070f4c291ce3890190733\">\n.flex_cell.av-1lhqgft-9ffe441c8ce070f4c291ce3890190733{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-1lhqgft-9ffe441c8ce070f4c291ce3890190733 av-gridrow-cell av_one_fifth no_margin av-hide-on-mobile  avia-builder-el-4  el_before_av_cell_three_fifth  avia-builder-el-first  content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1js30qx-481d5b1af4740e6c1ae48d1bb4896a08\">\n.flex_cell.av-1js30qx-481d5b1af4740e6c1ae48d1bb4896a08{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-1js30qx-481d5b1af4740e6c1ae48d1bb4896a08 av-gridrow-cell av_three_fifth no_margin  avia-builder-el-5  el_after_av_cell_one_fifth  el_before_av_cell_one_fifth  content-align-top'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1iim5a1-b646c6fb2606b6474487db3779f6dc88\">\n.avia-image-container.av-1iim5a1-b646c6fb2606b6474487db3779f6dc88 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1iim5a1-b646c6fb2606b6474487db3779f6dc88 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1iim5a1-b646c6fb2606b6474487db3779f6dc88 av-styling- av-img-linked avia-align-center  avia-builder-el-6  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg\" data-srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--600x338.jpg 600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Taburete Dalia Metal'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-39077 avia-img-lazy-loading-not-39077 avia_image ' src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg\" alt='taburete Dalia DOOS' title='Taburete Dalia Metal'  height=\"580\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--600x338.jpg 600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-58446x-096a90470ff95d9dbcd041820fc83f46\">\n.flex_cell.av-58446x-096a90470ff95d9dbcd041820fc83f46{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-58446x-096a90470ff95d9dbcd041820fc83f46 av-gridrow-cell av_one_fifth no_margin av-hide-on-mobile  avia-builder-el-7  el_after_av_cell_three_fifth  avia-builder-el-last  content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n<div id='av-layout-grid-2'  class='av-layout-grid-container av-1ebf47d-15c2dc3bc57f89f31dc578f79278d693 entry-content-wrapper main_color av-border-top-bottom av-flex-cells  avia-builder-el-8  el_after_av_layout_row  el_before_av_layout_row  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1derx3t-7eae03eee1bb5dd9e206a8240bd541c7\">\n.flex_cell.av-1derx3t-7eae03eee1bb5dd9e206a8240bd541c7{\nvertical-align:middle;\n}\n<\/style>\n<div class='flex_cell av-1derx3t-7eae03eee1bb5dd9e206a8240bd541c7 av-gridrow-cell av_one_fifth no_margin  avia-builder-el-9  el_before_av_cell_three_fifth  avia-builder-el-first  content-align-middle'  ><div class='flex_cell_inner'>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-19ouoah-9fa61e89caec1457a2591ae71d19358f\">\n.flex_cell.av-19ouoah-9fa61e89caec1457a2591ae71d19358f{\nvertical-align:middle;\n}\n<\/style>\n<div class='flex_cell av-19ouoah-9fa61e89caec1457a2591ae71d19358f av-gridrow-cell av_three_fifth no_margin  avia-builder-el-11  el_after_av_cell_one_fifth  el_before_av_cell_one_fifth  content-align-middle'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-18g63c9-841c788fecfd516315c9916c5fd95479\">\n.avia-image-container.av-18g63c9-841c788fecfd516315c9916c5fd95479 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-18g63c9-841c788fecfd516315c9916c5fd95479 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-18g63c9-841c788fecfd516315c9916c5fd95479 av-styling- av-img-linked avia-align-center  avia-builder-el-12  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma-.jpg\" data-srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma-.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--240x135.jpg 240w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Taburete Dalia Metal. Mesa 50 Pluma'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-39061 avia-img-lazy-loading-not-39061 avia_image ' src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma-.jpg\" alt='Mesa 50 Pluma DOOS' title='Taburete Dalia Metal. Mesa 50 Pluma'  height=\"580\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma-.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2023\/11\/Taburete-Dalia-Metal.-Mesa-50-Pluma--240x135.jpg 240w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-16cstvd-077ac85b76bc6bc8f01f489a8fa744e8\">\n.flex_cell.av-16cstvd-077ac85b76bc6bc8f01f489a8fa744e8{\nvertical-align:middle;\n}\n<\/style>\n<div class='flex_cell av-16cstvd-077ac85b76bc6bc8f01f489a8fa744e8 av-gridrow-cell av_one_fifth no_margin  avia-builder-el-13  el_after_av_cell_three_fifth  avia-builder-el-last  content-align-middle'  ><div class='flex_cell_inner'>\n<\/div><\/div>\n<\/div>\n<div id='av-layout-grid-3'  class='av-layout-grid-container av-12wyo1l-8777d54606228f3b7e54248acf032f24 entry-content-wrapper main_color av-border-top-bottom av-flex-cells  avia-builder-el-15  el_after_av_layout_row  el_before_av_layout_row  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-11jaord-f5b2052f6fa9729e79fc12bab3ac5e54\">\n.flex_cell.av-11jaord-f5b2052f6fa9729e79fc12bab3ac5e54{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-11jaord-f5b2052f6fa9729e79fc12bab3ac5e54 av-gridrow-cell av_one_fifth no_margin  avia-builder-el-16  el_before_av_cell_three_fifth  avia-builder-el-first  content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-y2qlah-09a678a5b289d3211759d757b801ec46\">\n.flex_cell.av-y2qlah-09a678a5b289d3211759d757b801ec46{\nvertical-align:middle;\n}\n.responsive #top #wrap_all .flex_cell.av-y2qlah-09a678a5b289d3211759d757b801ec46{\npadding:15px 15px 15px 15px !important;\n}\n<\/style>\n<div class='flex_cell av-y2qlah-09a678a5b289d3211759d757b801ec46 av-gridrow-cell av_three_fifth no_margin  avia-builder-el-17  el_after_av_cell_one_fifth  el_before_av_cell_one_fifth  content-align-middle'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l7u4sds4-7fd85c75b4cfd208315690de09e9fc66\">\n#top .av_textblock_section.av-l7u4sds4-7fd85c75b4cfd208315690de09e9fc66 .avia_textblock{\ntext-align:left;\n}\n<\/style>\n<section  class='av_textblock_section av-l7u4sds4-7fd85c75b4cfd208315690de09e9fc66 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.<\/p>\n<\/div><\/section><br \/>\n<div class='av-woo-product-info av-vv60ah-1f2862bc22240b2daf778d7f6ccd7262  avia-builder-el-19  el_after_av_textblock  avia-builder-el-last '><table class=\"woocommerce-product-attributes shop_attributes\" aria-label=\"Product Details\">\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_diseno\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Dise\u00f1o<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p>Enrique Mart\u00ed Associates<\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_descripcion\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Descripci\u00f3n<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p>Metal footrest, Metallic sled base, Several possible heights, without armrests, 12 mm rod<\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_uso\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Uso<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p>Corporate, Home, Interiors and public use<\/p>\n<\/td>\n\t\t<\/tr>\n\t<\/table>\n<\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2irqs9-8e7a055386d11138037fa486c92f3345\">\n.flex_cell.av-2irqs9-8e7a055386d11138037fa486c92f3345{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-2irqs9-8e7a055386d11138037fa486c92f3345 av-gridrow-cell av_one_fifth no_margin  avia-builder-el-20  el_after_av_cell_three_fifth  avia-builder-el-last  content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n<div id='av-layout-grid-4'  class='av-layout-grid-container av-ulj4rt-2a489d1f02455ad2d0f38f4b777b46f5 entry-content-wrapper main_color av-border-top-bottom av-flex-cells  avia-builder-el-21  el_after_av_layout_row  el_before_av_layout_row  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-sh8v15-c60162c8e29a7b06ba4c5889e0e2e4fc\">\n.flex_cell.av-sh8v15-c60162c8e29a7b06ba4c5889e0e2e4fc{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-sh8v15-c60162c8e29a7b06ba4c5889e0e2e4fc av-gridrow-cell av_one_fifth no_margin  avia-builder-el-22  el_before_av_cell_three_fifth  avia-builder-el-first  content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-rb2atl-b035e65b1895349c2ddc8af22be79774\">\n.flex_cell.av-rb2atl-b035e65b1895349c2ddc8af22be79774{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-rb2atl-b035e65b1895349c2ddc8af22be79774 av-gridrow-cell av_three_fifth no_margin  avia-builder-el-23  el_after_av_cell_one_fifth  el_before_av_cell_one_fifth  content-align-top'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-pclndl-db9739c2ebebee3c1793f9216a4c1fe1\">\n#top .hr.hr-invisible.av-pclndl-db9739c2ebebee3c1793f9216a4c1fe1{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-pclndl-db9739c2ebebee3c1793f9216a4c1fe1 hr-invisible  avia-builder-el-24  el_before_av_heading  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l7u4sq5k-da0c15825dd1d869236392bcad2172c0\">\n#top .av-special-heading.av-l7u4sq5k-da0c15825dd1d869236392bcad2172c0{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-l7u4sq5k-da0c15825dd1d869236392bcad2172c0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-l7u4sq5k-da0c15825dd1d869236392bcad2172c0 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-l7u4sq5k-da0c15825dd1d869236392bcad2172c0 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-25  el_after_av_hr  el_before_av_productgrid '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >DALIA COLLECTION<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-product-slider-container av-l7u4t0so-3d6a7ad6d15ada587314c859ce7a6dbf template-shop avia-content-slider avia-content-grid-active shop_columns_4  avia-builder-el-26  el_after_av_heading  avia-builder-el-last  avia-content-slider-even  avia-builder-el-26  el_after_av_heading  avia-builder-el-last  av-slideshow-ui av-slider-hover-pause av-slideshow-manual av-loop-once av-loop-manual-endless avia-product-slider1' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:true,&quot;show_slide_delay&quot;:0}\"><div class='avia-content-slider-inner'><ul class=\"products\"><li class=\"product type-product post-18209 status-publish first instock product_cat-chairs-doos product_cat-contract-en product_cat-dalia-chairs product_cat-dalia-collection has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/dalia-mr-chair\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-450x253.jpg\" class=\"wp-image-43921 avia-img-lazy-loading-43921 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"dalia mr silla DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-1030x579.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-1536x864.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-2048x1152.jpg 2048w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-1500x843.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-705x396.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-mr-silla-DOOS-1-1-600x337.jpg 600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DALIA MR<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-18198 status-publish instock product_cat-contract-en product_cat-dalia-collection product_cat-stools-doos has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" fetchpriority=\"high\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg\" class=\"wp-image-39077 avia-img-lazy-loading-not-39077 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"taburete Dalia DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg 1030w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DALIA METAL<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-32605 status-publish instock product_cat-chairs-doos product_cat-contract-en product_cat-dalia-chairs product_cat-dalia-collection has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/dalia-pp-chair\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-450x253.jpg\" class=\"wp-image-40384 avia-img-lazy-loading-40384 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"DOOS. Silla Dalia PP.\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-768x433.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-1536x866.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-1500x845.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3-600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-pp-3.jpg 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DALIA PP<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-18200 status-publish last instock product_cat-chairs-doos product_cat-contract-en product_cat-dalia-chairs product_cat-dalia-collection has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/dalia-ph-chair\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-450x253.jpg\" class=\"wp-image-40367 avia-img-lazy-loading-40367 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"DOOS. Silla Dalia PH.\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-768x433.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-1536x866.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-1500x845.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2-600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/dalia-ph-2.jpg 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DALIA PH<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<\/ul><\/div><\/div><div class=\"clear\"><\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nib161-f92e935ccfcd6a981c55b024a7a2ff2e\">\n.flex_cell.av-nib161-f92e935ccfcd6a981c55b024a7a2ff2e{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-nib161-f92e935ccfcd6a981c55b024a7a2ff2e av-gridrow-cell av_one_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-5'  class='av-layout-grid-container av-mqb8ax-b6badf3abc01889f36a1e0ece8d9ec0c entry-content-wrapper main_color av-border-top-bottom av-flex-cells  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-20238p-8afc6172afa85dbc724a79844c79dfac\">\n.flex_cell.av-20238p-8afc6172afa85dbc724a79844c79dfac{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-20238p-8afc6172afa85dbc724a79844c79dfac av-gridrow-cell av_one_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1ydfll-7f5c5e0854867671a3d70e185d7669d0\">\n.flex_cell.av-1ydfll-7f5c5e0854867671a3d70e185d7669d0{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-1ydfll-7f5c5e0854867671a3d70e185d7669d0 av-gridrow-cell av_three_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1s50w9-9e4bed8b1d9416ccc5b57e7012348076\">\n#top .hr.hr-invisible.av-1s50w9-9e4bed8b1d9416ccc5b57e7012348076{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-1s50w9-9e4bed8b1d9416ccc5b57e7012348076 hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<article  class='iconbox iconbox_top av-g31jpl-87de485fa0bc5e88b3173d50552c55d0 main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: WHERE TO BUY\"><a href='https:\/\/doosdesign.es\/en\/where-to-buy\/' title='WHERE TO BUY' aria-label='WHERE TO BUY'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue827' data-av_iconfont='entypo-fontello' title=\"WHERE TO BUY\" desc=\"WHERE TO BUY\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/doosdesign.es\/en\/where-to-buy\/' title='WHERE TO BUY' >WHERE TO BUY<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>You can purchase our products through our network of dealers. By consulting a dealer you will have professional advice and all the information about the product, prices and applications.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n<div  class='avia-button-wrap av-e4mtpl-5438bf7ed59fb79af69bf9a9dc782ac5-wrap avia-button-center '><a href='https:\/\/doosdesign.es\/en\/where-to-buy\/'  class='avia-button av-e4mtpl-5438bf7ed59fb79af69bf9a9dc782ac5 av-link-btn avia-icon_select-no avia-size-medium avia-position-center avia-color-theme-color'   aria-label=\"DEALERS\"><span class='avia_iconbox_title' >DEALERS<\/span><\/a><\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bva5m1-a1a2c17dcd46baaf112a8a7c609d3a3f\">\n.flex_cell.av-bva5m1-a1a2c17dcd46baaf112a8a7c609d3a3f{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-bva5m1-a1a2c17dcd46baaf112a8a7c609d3a3f av-gridrow-cell av_one_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-6'  class='av-layout-grid-container av-api63d-059bc4e1b84f82cf8c9aae4c6be2a745 entry-content-wrapper main_color av-border-top-bottom av-flex-cells  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9r3j1l-69b286aed8832c76e749dec120df1dac\">\n.flex_cell.av-9r3j1l-69b286aed8832c76e749dec120df1dac{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-9r3j1l-69b286aed8832c76e749dec120df1dac av-gridrow-cell av_one_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-78fn1l-b82f3affc1c12447c71b809920597ffb\">\n.flex_cell.av-78fn1l-b82f3affc1c12447c71b809920597ffb{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-78fn1l-b82f3affc1c12447c71b809920597ffb av-gridrow-cell av_three_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-61cppl-e51cb95ad690038edd6b6ddf5912811e\">\n#top .hr.hr-invisible.av-61cppl-e51cb95ad690038edd6b6ddf5912811e{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-61cppl-e51cb95ad690038edd6b6ddf5912811e hr-invisible'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-49mou1-096a94712016ef49d6d24f5c359eb8bd\">\n#top .av-special-heading.av-49mou1-096a94712016ef49d6d24f5c359eb8bd{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-49mou1-096a94712016ef49d6d24f5c359eb8bd .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-49mou1-096a94712016ef49d6d24f5c359eb8bd .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-49mou1-096a94712016ef49d6d24f5c359eb8bd av-special-heading-h2 blockquote modern-quote modern-centered'><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >OTHER PRODUCTS<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-product-slider-container av-l7u4te22-068ce4772aad921525bc1c762655cdc4 template-shop avia-content-slider avia-content-grid-active shop_columns_5 avia-content-slider-odd av-slideshow-ui av-slider-hover-pause av-slideshow-manual av-loop-once av-loop-manual-endless avia-product-slider2' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:true,&quot;show_slide_delay&quot;:0}\"><div class='avia-content-slider-inner'><ul class=\"products\"><li class=\"product type-product post-28982 status-publish first instock product_cat-blur-collection product_cat-contract-en product_cat-new product_cat-stools-doos has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/blur-t02-metal-with-backrest-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-450x253.jpg\" class=\"wp-image-38412 avia-img-lazy-loading-38412 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"Blur taburete con respaldo metal DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-1536x864.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-2048x1152.jpg 2048w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-1500x844.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-metal-600x338.jpg 600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">BLUR METAL WITH BACKREST<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-38489 status-publish instock product_cat-collection-neo-en product_cat-contract-en product_cat-neo-stools product_cat-new product_cat-stools-doos product_cat-top-sales-january23-june24 has-post-thumbnail featured shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/neo-t01-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-450x253.jpg\" class=\"wp-image-41479 avia-img-lazy-loading-41479 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"neo taburete madera DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-768x433.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-1536x865.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-2048x1153.jpg 2048w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-1500x845.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-madera-DOOS-600x338.jpg 600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">NEO WOOD<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-18198 status-publish instock product_cat-contract-en product_cat-dalia-collection product_cat-stools-doos has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" fetchpriority=\"high\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg\" class=\"wp-image-39077 avia-img-lazy-loading-not-39077 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"taburete Dalia DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal--600x338.jpg 600w, https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg 1030w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DALIA METAL<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-38488 status-publish instock product_cat-collection-neo-en product_cat-contract-en product_cat-neo-stools product_cat-new product_cat-stools-doos product_cat-top-sales-january23-june24 has-post-thumbnail featured shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/neo-t02-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-450x253.jpg\" class=\"wp-image-41482 avia-img-lazy-loading-41482 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"neo taburete metal DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-768x433.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-1536x865.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-2048x1153.jpg 2048w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-1500x845.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2024\/01\/neo-taburete-metal-DOOS-600x338.jpg 600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">NEO METAL<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-28984 status-publish last instock product_cat-blur-collection product_cat-contract-en product_cat-new product_cat-stools-doos has-post-thumbnail featured shipping-taxable product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-minimal'><a href=\"https:\/\/doosdesign.es\/en\/products\/blur-t01-wood-with-backrest-stool\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"253\" src=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-450x253.jpg\" class=\"wp-image-38409 avia-img-lazy-loading-38409 attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-post-image\" alt=\"Blur taburete con respaldo madera DOOS\" srcset=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-450x253.jpg 450w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-300x169.jpg 300w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-768x432.jpg 768w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-1030x580.jpg 1030w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-1536x864.jpg 1536w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-2048x1152.jpg 2048w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-1500x844.jpg 1500w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-705x397.jpg 705w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-240x135.jpg 240w, https:\/\/doosdesign.es\/wp-content\/uploads\/2022\/08\/blur-taburete-con-respaldo-madera-600x338.jpg 600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">BLUR WOOD WITH BACKREST<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<\/ul><\/div><\/div><div class=\"clear\"><\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-31091l-f901e396f6d80d4dca4bb85ad4778f37\">\n.flex_cell.av-31091l-f901e396f6d80d4dca4bb85ad4778f37{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-31091l-f901e396f6d80d4dca4bb85ad4778f37 av-gridrow-cell av_one_fifth no_margin content-align-top'  ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":39077,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[871,877,883],"product_tag":[],"class_list":{"0":"post-18198","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-contract-en","7":"product_cat-dalia-collection","8":"product_cat-stools-doos","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DALIA METAL - DOOS design<\/title>\n<meta name=\"description\" content=\"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DALIA METAL - DOOS design\" \/>\n<meta property=\"og:description\" content=\"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/\" \/>\n<meta property=\"og:site_name\" content=\"DOOS design\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T07:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"31 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/\",\"url\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/\",\"name\":\"DALIA METAL - DOOS design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/doosdesign.es\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Taburete-Dalia-Metal-.jpg\",\"datePublished\":\"2019-12-09T09:55:47+00:00\",\"dateModified\":\"2025-02-10T07:18:31+00:00\",\"description\":\"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/doosdesign.es\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Taburete-Dalia-Metal-.jpg\",\"contentUrl\":\"https:\\\/\\\/doosdesign.es\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Taburete-Dalia-Metal-.jpg\",\"width\":1030,\"height\":580,\"caption\":\"taburete Dalia DOOS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/products\\\/dalia-t02-stool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/contemporary-modern-furniture-design\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pagina de tienda\",\"item\":\"https:\\\/\\\/doosdesign.es\\\/?page_id=1806\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stools\",\"item\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/catalogo\\\/stools-doos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"DALIA METAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/\",\"name\":\"DOOS design\",\"description\":\"Muebles de dise\u00f1o para hogar y contract: sillas, sillones, taburetes, butacas, mesas y mesas de centro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#organization\",\"name\":\"DOOS\",\"url\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/doosdesign.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-doos2.png\",\"contentUrl\":\"https:\\\/\\\/doosdesign.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-doos2.png\",\"width\":340,\"height\":156,\"caption\":\"DOOS\"},\"image\":{\"@id\":\"https:\\\/\\\/doosdesign.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/doosdesign\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCrkeO-E4F-BE7nKVpW1cAlw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DALIA METAL - DOOS design","description":"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/","og_locale":"en_US","og_type":"article","og_title":"DALIA METAL - DOOS design","og_description":"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.","og_url":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/","og_site_name":"DOOS design","article_modified_time":"2025-02-10T07:18:31+00:00","og_image":[{"width":1030,"height":580,"url":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"31 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/","url":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/","name":"DALIA METAL - DOOS design","isPartOf":{"@id":"https:\/\/doosdesign.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/#primaryimage"},"image":{"@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/#primaryimage"},"thumbnailUrl":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg","datePublished":"2019-12-09T09:55:47+00:00","dateModified":"2025-02-10T07:18:31+00:00","description":"DALIA are functional and adaptable seats. Highly resistant and durable, they are designed for continuous use and very easy maintenance.","breadcrumb":{"@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/#primaryimage","url":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg","contentUrl":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/12\/Taburete-Dalia-Metal-.jpg","width":1030,"height":580,"caption":"taburete Dalia DOOS"},{"@type":"BreadcrumbList","@id":"https:\/\/doosdesign.es\/en\/products\/dalia-t02-stool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/doosdesign.es\/en\/contemporary-modern-furniture-design\/"},{"@type":"ListItem","position":2,"name":"pagina de tienda","item":"https:\/\/doosdesign.es\/?page_id=1806"},{"@type":"ListItem","position":3,"name":"Stools","item":"https:\/\/doosdesign.es\/en\/catalogo\/stools-doos\/"},{"@type":"ListItem","position":4,"name":"DALIA METAL"}]},{"@type":"WebSite","@id":"https:\/\/doosdesign.es\/en\/#website","url":"https:\/\/doosdesign.es\/en\/","name":"DOOS design","description":"Muebles de dise\u00f1o para hogar y contract: sillas, sillones, taburetes, butacas, mesas y mesas de centro.","publisher":{"@id":"https:\/\/doosdesign.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/doosdesign.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/doosdesign.es\/en\/#organization","name":"DOOS","url":"https:\/\/doosdesign.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/doosdesign.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/05\/logo-doos2.png","contentUrl":"https:\/\/doosdesign.es\/wp-content\/uploads\/2019\/05\/logo-doos2.png","width":340,"height":156,"caption":"DOOS"},"image":{"@id":"https:\/\/doosdesign.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/doosdesign\/","https:\/\/www.youtube.com\/channel\/UCrkeO-E4F-BE7nKVpW1cAlw"]}]}},"_links":{"self":[{"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/product\/18198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/comments?post=18198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/media\/39077"}],"wp:attachment":[{"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/media?parent=18198"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/product_brand?post=18198"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/product_cat?post=18198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/doosdesign.es\/en\/wp-json\/wp\/v2\/product_tag?post=18198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}